{"id":40,"count":1,"description":"","link":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr","name":"Feuerwehr","slug":"feuerwehr","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feuerwehr Archive - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen<\/title>\n<meta name=\"description\" content=\"Kategorien deutsch-polnischer Themen aus Wielu\u0144 und Adelebsen und dar\u00fcber hinaus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feuerwehr Archive - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\" \/>\n<meta property=\"og:description\" content=\"Kategorien deutsch-polnischer Themen aus Wielu\u0144 und Adelebsen und dar\u00fcber hinaus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr\" \/>\n<meta property=\"og:site_name\" content=\"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/feuerwehr\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/feuerwehr\",\"name\":\"Feuerwehr Archive - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#website\"},\"description\":\"Kategorien deutsch-polnischer Themen aus Wielu\u0144 und Adelebsen und dar\u00fcber hinaus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/feuerwehr#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/feuerwehr#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feuerwehr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/\",\"name\":\"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\",\"description\":\"Stowarzyszenie partnerskie Adelebsen\",\"publisher\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#organization\",\"name\":\"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V.\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/pv-logo-06.png\",\"contentUrl\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/pv-logo-06.png\",\"width\":544,\"height\":674,\"caption\":\"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/Partnerschaftsverein.Adelebsen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feuerwehr Archive - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","description":"Kategorien deutsch-polnischer Themen aus Wielu\u0144 und Adelebsen und dar\u00fcber hinaus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr","og_locale":"pl_PL","og_type":"article","og_title":"Feuerwehr Archive - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","og_description":"Kategorien deutsch-polnischer Themen aus Wielu\u0144 und Adelebsen und dar\u00fcber hinaus","og_url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr","og_site_name":"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr","url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr","name":"Feuerwehr Archive - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","isPartOf":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#website"},"description":"Kategorien deutsch-polnischer Themen aus Wielu\u0144 und Adelebsen und dar\u00fcber hinaus","breadcrumb":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/feuerwehr#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/"},{"@type":"ListItem","position":2,"name":"Feuerwehr"}]},{"@type":"WebSite","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#website","url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/","name":"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","description":"Stowarzyszenie partnerskie Adelebsen","publisher":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#organization","name":"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V.","url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2016\/08\/pv-logo-06.png","contentUrl":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2016\/08\/pv-logo-06.png","width":544,"height":674,"caption":"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V."},"image":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/Partnerschaftsverein.Adelebsen\/"]}]}},"_links":{"self":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/categories\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/posts?categories=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}