{"id":451936,"date":"2020-11-26T14:39:42","date_gmt":"2020-11-26T13:39:42","guid":{"rendered":"https:\/\/partnerschaftsverein-adelebsen.de\/?p=451936"},"modified":"2021-05-30T06:13:47","modified_gmt":"2021-05-30T04:13:47","slug":"bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023","status":"publish","type":"post","link":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023","title":{"rendered":"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c &#8211; Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023"},"content":{"rendered":"<p><span style=\"color: #800000;\"><em>Okres rejestracji wygas\u0142&#8230;<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/pl.wikipedia.org\/wiki\/Polsko-Niemiecka_Wsp%C3%B3%C5%82praca_M%C5%82odzie%C5%BCy\" target=\"_blank\" rel=\"noopener noreferrer\">Polsko-Niemiecka Wsp\u00f3\u0142praca M\u0142odzie\u017cy<\/a> (PNWM) zaprasza do udzia\u0142u w konkursie o Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 realizowanego pod has\u0142em \u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c. Konkurs jest skierowany do organizacji i instytucji realizuj\u0105cych polsko-niemieckie projekty wymiany m\u0142odzie\u017cy. Projekty mo\u017cna zg\u0142asza\u0107 do 28 lutego 2021 roku.<\/p>\n<p style=\"text-align: justify;\">S\u0105 Pa\u0144stwo szko\u0142\u0105, stowarzyszeniem lub organizacj\u0105 pozarz\u0105dow\u0105, kt\u00f3ra chcia\u0142aby anga\u017cowa\u0107 si\u0119 w&nbsp;\u017cycie miejscowej spo\u0142eczno\u015bci? Chcieliby Pa\u0144stwo przybli\u017cy\u0107 lokalnym mieszka\u0144com swoj\u0105 dzia\u0142alno\u015b\u0107 i zaprosi\u0107 ich do wsp\u00f3\u0142pracy lub z m\u0142odzie\u017c\u0105 zrobi\u0107 co\u015b dla swojej wsi, miasta lub powiatu? Poza tym maj\u0105 Pa\u0144stwo partnera w Niemczech, kt\u00f3ry r\u00f3wnie\u017c dzia\u0142a lokalnie i chcieliby Pa\u0144stwo wsp\u00f3lnie zrealizowa\u0107 projekt&nbsp;po\u015bwi\u0119cony Pa\u0144stwa miejscowo\u015bciom lub regionom? PNWM zaprasza wi\u0119c Pa\u0144stwa do zg\u0142oszenia&nbsp;wybranego pomys\u0142u na projekt do konkursu o Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023.<\/p>\n<ul>\n<li><strong>Strona internetowa<\/strong> polski:&nbsp;<em><a href=\"https:\/\/pnwm.org\/program-spotkania-mlodziezy-w-ramach-polsko-niemieckich-partnerstw-gmin-i-powiatow\/\" target=\"_blank\" rel=\"noopener noreferrer\">pnwm.org\/program-spotkania-mlodziezy-w-ramach-polsko-niemieckich-partnerstw-gmin-i-powiatow<\/a><\/em> i niemiecki: <em><a href=\"https:\/\/dpjw.org\/dpjw\/jugendpreis\/\" target=\"_blank\" rel=\"noopener noreferrer\">dpjw.org\/dpjw\/jugendpreis<\/a> <i><strong><a href=\"https:\/\/www.facebook.com\/DPJWPNWM\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-408352\" src=\"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/06\/240px-Facebook_f_logo_2019.svg_-150x150.png\" alt=\"\" width=\"18\" height=\"18\" srcset=\"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/06\/240px-Facebook_f_logo_2019.svg_-150x150.png 150w, https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/06\/240px-Facebook_f_logo_2019.svg_-200x200.png 200w, https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/06\/240px-Facebook_f_logo_2019.svg_.png 240w\" sizes=\"auto, (max-width: 18px) 100vw, 18px\" \/><\/a><\/strong><\/i><\/em><\/li>\n<li><strong>Rejestracja<\/strong> do 28 lutego 2021 r. Za pomoc\u0105 formularza internetowego polski: <em><a href=\"https:\/\/web.archive.org\/web\/20210301044120\/https:\/\/wiki.dpjw.org\/webform7\/pl\/node\/255\" target=\"_blank\" rel=\"noopener noreferrer\">wiki.dpjw.org\/webform7\/pl\/node\/255<\/a><\/em> i niemiecki: <em><a href=\"https:\/\/web.archive.org\/web\/20210301044838\/https:\/\/wiki.dpjw.org\/webform7\/de\/node\/251\" target=\"_blank\" rel=\"noopener noreferrer\">wiki.dpjw.org\/webform7\/de\/node\/251<\/a><\/em><\/li>\n<li><strong>Ulotka o konkursie<\/strong> polski: <em><a href=\"https:\/\/pnwm.org\/wp-content\/uploads\/2020\/10\/Ulotka-Polsko-Niemiecka-Nagroda-Mlodziezy-2021-2023_nwe.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">pnwm.org\/&#8230;\/Ulotka-Polsko-Niemiecka-Nagroda-Mlodziezy-2021-2023_&#8230;.pdf<\/a><\/em> i niemiecki: <em><a href=\"https:\/\/dpjw.org\/wp-content\/uploads\/2020\/10\/Flyer-Deutsch-Polnischer-Jugendpreis-2021-2023_new.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">dpjw.org\/&#8230;\/Flyer-Deutsch-Polnischer-Jugendpreis-2021-2023_&#8230;.pdf<\/a><\/em><\/li>\n<li><strong>Regulamin konkursu<\/strong>: <em><a href=\"https:\/\/dpjw.org\/wp-content\/uploads\/2020\/10\/Regulamin-konkursu-o-Polsko-Niemiecka-Nagrode-Mlodziezy-2021-2023.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">dpjw.org\/&#8230;\/Regulamin-konkursu-o-Polsko-Niemiecka-Nagrode-Mlodziezy-2021-2023.pdf<\/a><\/em><br \/>\n&nbsp;<\/li>\n<li><strong>Kontakt<\/strong>: Pani Maria Albers, Kierowniczka referatu koordynacji<br \/>\nTel.: +48 22 518 89 15<br \/>\nE-mail: <a href=\"mailto:j&#117;&#103;&#101;&#110;d&#112;&#114;ei&#115;&#64;dpjw&#46;&#111;rg\">&#106;&#117;&#103;&#101;&#110;d&#112;re&#105;&#115;&#64;d&#112;j&#119;&#46;&#111;rg<\/a><\/li>\n<\/ul>\n<p><em>Stowarzyszenie partnerskie Adelebsen r\u00f3wnie\u017c \u017cyczy powodzenia!<\/em><\/p>\n<div class=\"shariff\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=%E2%80%9EU%20mnie%20i%20u%20Ciebie.%20Wymiana%20m%C5%82odzie%C5%BCy%20lokalnie%E2%80%9C%20%E2%80%93%20Polsko-Niemieck%C4%85%20Nagrod%C4%99%20M%C5%82odzie%C5%BCy%202021-2023 https%3A%2F%2Fpartnerschaftsverein-adelebsen.de%2Fpl%2Fbei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\" title=\"Udost\u0119pnij na Mastodonu\" aria-label=\"Udost\u0119pnij na Mastodonu\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">udost\u0119pnij<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fpartnerschaftsverein-adelebsen.de%2Fpl%2Fbei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\" title=\"Udost\u0119pnij na Facebooku\" aria-label=\"Udost\u0119pnij na Facebooku\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">udost\u0119pnij<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fpartnerschaftsverein-adelebsen.de%2Fpl%2Fbei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\" title=\"Udost\u0119pnij przez LinkedIn\" aria-label=\"Udost\u0119pnij przez LinkedIn\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">udost\u0119pnij<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Wi\u0119cej informacji\" aria-label=\"Wi\u0119cej informacji\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Polsko-Niemiecka Wsp\u00f3\u0142praca M\u0142odzie\u017cy (PNWM) zaprasza do udzia\u0142u w konkursie o Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 realizowanego pod has\u0142em \u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c &#8211; <a class=\"more-link\" href=\"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\">weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":451953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,59],"tags":[],"class_list":["post-451936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-austausch","category-jugendarbeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c - Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen<\/title>\n<meta name=\"description\" content=\"Beitr\u00e4ge zu deutsch-polnischen Themen und Nachrichten aus Wielun und Adelebsen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c - Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\" \/>\n<meta property=\"og:description\" content=\"Beitr\u00e4ge zu deutsch-polnischen Themen und Nachrichten aus Wielun und Adelebsen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\" \/>\n<meta property=\"og:site_name\" content=\"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/Partnerschaftsverein.Adelebsen\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-26T13:39:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-30T04:13:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/11\/jugendpreis2_w.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/#\\\/schema\\\/person\\\/bab091e93b111d8d5afd64f42100541a\"},\"headline\":\"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c &#8211; Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023\",\"datePublished\":\"2020-11-26T13:39:42+00:00\",\"dateModified\":\"2021-05-30T04:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\"},\"wordCount\":760,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jugendpreis2_w.jpg\",\"articleSection\":[\"Austausch\",\"Jugendarbeit\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\",\"name\":\"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c - Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jugendpreis2_w.jpg\",\"datePublished\":\"2020-11-26T13:39:42+00:00\",\"dateModified\":\"2021-05-30T04:13:47+00:00\",\"description\":\"Beitr\u00e4ge zu deutsch-polnischen Themen und Nachrichten aus Wielun und Adelebsen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jugendpreis2_w.jpg\",\"contentUrl\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jugendpreis2_w.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c &#8211; Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/\",\"name\":\"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen\",\"description\":\"Stowarzyszenie partnerskie Adelebsen\",\"publisher\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#organization\",\"name\":\"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V.\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/pv-logo-06.png\",\"contentUrl\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/pv-logo-06.png\",\"width\":544,\"height\":674,\"caption\":\"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/Partnerschaftsverein.Adelebsen\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/#\\\/schema\\\/person\\\/bab091e93b111d8d5afd64f42100541a\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13de98f03b2bcf18f40f04d5aa452a922c72047c6c1fe230a5ee80361788e7d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13de98f03b2bcf18f40f04d5aa452a922c72047c6c1fe230a5ee80361788e7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13de98f03b2bcf18f40f04d5aa452a922c72047c6c1fe230a5ee80361788e7d8?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"url\":\"https:\\\/\\\/partnerschaftsverein-adelebsen.de\\\/pl\\\/author\\\/redaktion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c - Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","description":"Beitr\u00e4ge zu deutsch-polnischen Themen und Nachrichten aus Wielun und Adelebsen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023","og_locale":"pl_PL","og_type":"article","og_title":"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c - Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","og_description":"Beitr\u00e4ge zu deutsch-polnischen Themen und Nachrichten aus Wielun und Adelebsen.","og_url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023","og_site_name":"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","article_publisher":"https:\/\/www.facebook.com\/groups\/Partnerschaftsverein.Adelebsen\/","article_published_time":"2020-11-26T13:39:42+00:00","article_modified_time":"2021-05-30T04:13:47+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/11\/jugendpreis2_w.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Redaktion","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#article","isPartOf":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023"},"author":{"name":"Redaktion","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/#\/schema\/person\/bab091e93b111d8d5afd64f42100541a"},"headline":"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c &#8211; Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023","datePublished":"2020-11-26T13:39:42+00:00","dateModified":"2021-05-30T04:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023"},"wordCount":760,"commentCount":0,"publisher":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/#organization"},"image":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage"},"thumbnailUrl":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/11\/jugendpreis2_w.jpg","articleSection":["Austausch","Jugendarbeit"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#respond"]}]},{"@type":"WebPage","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023","url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023","name":"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c - Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023 - Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","isPartOf":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage"},"image":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage"},"thumbnailUrl":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/11\/jugendpreis2_w.jpg","datePublished":"2020-11-26T13:39:42+00:00","dateModified":"2021-05-30T04:13:47+00:00","description":"Beitr\u00e4ge zu deutsch-polnischen Themen und Nachrichten aus Wielun und Adelebsen.","breadcrumb":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023"]]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#primaryimage","url":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/11\/jugendpreis2_w.jpg","contentUrl":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2020\/11\/jugendpreis2_w.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/bei-mir-und-bei-dir-jugendaustausch-lokal-deutsch-polnischer-jugendpreis-2021-2023#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/"},{"@type":"ListItem","position":2,"name":"\u201eU mnie i u Ciebie. Wymiana m\u0142odzie\u017cy lokalnie\u201c &#8211; Polsko-Niemieck\u0105 Nagrod\u0119 M\u0142odzie\u017cy 2021-2023"}]},{"@type":"WebSite","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#website","url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/","name":"Partnerstwo Ostr\u00f3wek, Wielu\u0144 &amp; Adelebsen","description":"Stowarzyszenie partnerskie Adelebsen","publisher":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#organization","name":"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V.","url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2016\/08\/pv-logo-06.png","contentUrl":"https:\/\/partnerschaftsverein-adelebsen.de\/wp-content\/uploads\/2016\/08\/pv-logo-06.png","width":544,"height":674,"caption":"F\u00f6rderverein der Partnerschaften Ostrowek, Wielun und Adelebsen e.V."},"image":{"@id":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/Partnerschaftsverein.Adelebsen\/"]},{"@type":"Person","@id":"https:\/\/partnerschaftsverein-adelebsen.de\/#\/schema\/person\/bab091e93b111d8d5afd64f42100541a","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/secure.gravatar.com\/avatar\/13de98f03b2bcf18f40f04d5aa452a922c72047c6c1fe230a5ee80361788e7d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/13de98f03b2bcf18f40f04d5aa452a922c72047c6c1fe230a5ee80361788e7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13de98f03b2bcf18f40f04d5aa452a922c72047c6c1fe230a5ee80361788e7d8?s=96&d=mm&r=g","caption":"Redaktion"},"url":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/author\/redaktion"}]}},"_links":{"self":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/posts\/451936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/comments?post=451936"}],"version-history":[{"count":0,"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/posts\/451936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/media\/451953"}],"wp:attachment":[{"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/media?parent=451936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/categories?post=451936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/partnerschaftsverein-adelebsen.de\/pl\/wp-json\/wp\/v2\/tags?post=451936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}